{"id":8298,"date":"2026-05-12T22:47:00","date_gmt":"2026-05-12T21:47:00","guid":{"rendered":"https:\/\/isimarkets.com\/?p=8298"},"modified":"2026-05-12T22:52:10","modified_gmt":"2026-05-12T21:52:10","slug":"el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia","status":"publish","type":"post","link":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/","title":{"rendered":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda."},"content":{"rendered":"\n<p>Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"412\" src=\"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/How-a-corruption-scandal-rocked-the-Philippine-economy-lower-energy-use-reflects-stalled-projects-1-1024x412.png\" alt=\"\" class=\"wp-image-8292\" srcset=\"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/How-a-corruption-scandal-rocked-the-Philippine-economy-lower-energy-use-reflects-stalled-projects-1-1024x412.png 1024w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/How-a-corruption-scandal-rocked-the-Philippine-economy-lower-energy-use-reflects-stalled-projects-1-300x121.png 300w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/How-a-corruption-scandal-rocked-the-Philippine-economy-lower-energy-use-reflects-stalled-projects-1-768x309.png 768w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/How-a-corruption-scandal-rocked-the-Philippine-economy-lower-energy-use-reflects-stalled-projects-1.png 1294w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Las acusaciones de corrupci\u00f3n surgieron en 2024 y ganaron mayor visibilidad a mediados de 2025. Es a partir de ese momento cuando los cambios empiezan a reflejarse con mayor claridad en los datos.<\/p>\n\n\n\n<p>Con varios proyectos importantes detenidos, las importaciones de petr\u00f3leo y el consumo de electricidad comenzaron a caer. Al mismo tiempo, el gasto de capital del gobierno entr\u00f3 en una fase prolongada de contracci\u00f3n interanual.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"416\" src=\"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings-1-1024x416.png\" alt=\"\" class=\"wp-image-8293\" srcset=\"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings-1-1024x416.png 1024w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings-1-300x122.png 300w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings-1-768x312.png 768w, https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings-1.png 1294w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real. Las acusaciones de corrupci\u00f3n surgieron en 2024 y ganaron mayor visibilidad a&hellip;<\/p>\n","protected":false},"author":20,"featured_media":8297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","cpa_authors":[],"cpa_override_default":false,"footnotes":""},"categories":[1119],"tags":[1134],"product":[1056],"region":[954],"class_list":["post-8298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications","tag-corrupcion","product-ceic","region-asean"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin  - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda. - ISI<\/title>\n<meta name=\"description\" content=\"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda.\" \/>\n<meta property=\"og:description\" content=\"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/\" \/>\n<meta property=\"og:site_name\" content=\"ISI\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T21:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T21:52:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1294\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Cuello Franco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/\"},\"author\":{\"name\":\"Ana Cuello Franco\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#\\\/schema\\\/person\\\/5785de41521216af0b9318f408bd5e10\"},\"headline\":\"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda.\",\"datePublished\":\"2026-05-12T21:47:00+00:00\",\"dateModified\":\"2026-05-12T21:52:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/\"},\"wordCount\":147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png\",\"keywords\":[\"Corrupci\u00f3n\"],\"articleSection\":[\"Publications\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/\",\"url\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/\",\"name\":\"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda. - ISI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png\",\"datePublished\":\"2026-05-12T21:47:00+00:00\",\"dateModified\":\"2026-05-12T21:52:10+00:00\",\"description\":\"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png\",\"contentUrl\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png\",\"width\":1294,\"height\":526,\"caption\":\"Daily-electricity-data-captures-Philippine-economys-regional-swings\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/publications\\\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/\",\"name\":\"ISI\",\"description\":\"Global Market Intelligence Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#organization\",\"name\":\"ISI\",\"url\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ISI-Favicon-Logo-512px.webp\",\"contentUrl\":\"https:\\\/\\\/isimarkets.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ISI-Favicon-Logo-512px.webp\",\"width\":512,\"height\":512,\"caption\":\"ISI\"},\"image\":{\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/isi-markets\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/#\\\/schema\\\/person\\\/5785de41521216af0b9318f408bd5e10\",\"name\":\"Ana Cuello Franco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g\",\"caption\":\"Ana Cuello Franco\"},\"url\":\"https:\\\/\\\/isimarkets.com\\\/es\\\/author\\\/ana-cuello-franco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda. - ISI","description":"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/","og_locale":"es_ES","og_type":"article","og_title":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda.","og_description":"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.","og_url":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/","og_site_name":"ISI","article_published_time":"2026-05-12T21:47:00+00:00","article_modified_time":"2026-05-12T21:52:10+00:00","og_image":[{"width":1294,"height":526,"url":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Cuello Franco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#article","isPartOf":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/"},"author":{"name":"Ana Cuello Franco","@id":"https:\/\/isimarkets.com\/es\/#\/schema\/person\/5785de41521216af0b9318f408bd5e10"},"headline":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda.","datePublished":"2026-05-12T21:47:00+00:00","dateModified":"2026-05-12T21:52:10+00:00","mainEntityOfPage":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/"},"wordCount":147,"commentCount":0,"publisher":{"@id":"https:\/\/isimarkets.com\/es\/#organization"},"image":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png","keywords":["Corrupci\u00f3n"],"articleSection":["Publications"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/","url":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/","name":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda. - ISI","isPartOf":{"@id":"https:\/\/isimarkets.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#primaryimage"},"image":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png","datePublished":"2026-05-12T21:47:00+00:00","dateModified":"2026-05-12T21:52:10+00:00","description":"Nuestra base de datos ASEAN Premium est\u00e1 ayudando a identificar nuevas se\u00f1ales en una de las regiones m\u00e1s din\u00e1micas del mundo. En esta ocasi\u00f3n, el foco est\u00e1 en Filipinas, donde un esc\u00e1ndalo ligado a grandes proyectos de control de inundaciones est\u00e1 teniendo efectos claros sobre la econom\u00eda real.","breadcrumb":{"@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#primaryimage","url":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png","contentUrl":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/05\/Daily-electricity-data-captures-Philippine-economys-regional-swings.png","width":1294,"height":526,"caption":"Daily-electricity-data-captures-Philippine-economys-regional-swings"},{"@type":"BreadcrumbList","@id":"https:\/\/isimarkets.com\/es\/publications\/el-escandalo-en-filipinas-ha-frenado-los-proyectos-del-estado-y-tambien-ha-provocado-una-caida-en-el-consumo-de-energia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/isimarkets.com\/es\/"},{"@type":"ListItem","position":2,"name":"El esc\u00e1ndalo en Filipinas ha frenado los proyectos del Estado y tambi\u00e9n ha provocado una ca\u00edda en el consumo de energ\u00eda."}]},{"@type":"WebSite","@id":"https:\/\/isimarkets.com\/es\/#website","url":"https:\/\/isimarkets.com\/es\/","name":"ISI","description":"Global Market Intelligence Platform","publisher":{"@id":"https:\/\/isimarkets.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isimarkets.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/isimarkets.com\/es\/#organization","name":"ISI","url":"https:\/\/isimarkets.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/isimarkets.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/03\/ISI-Favicon-Logo-512px.webp","contentUrl":"https:\/\/isimarkets.com\/wp-content\/uploads\/2026\/03\/ISI-Favicon-Logo-512px.webp","width":512,"height":512,"caption":"ISI"},"image":{"@id":"https:\/\/isimarkets.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/isi-markets\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/isimarkets.com\/es\/#\/schema\/person\/5785de41521216af0b9318f408bd5e10","name":"Ana Cuello Franco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/821f9b01fdfd567c72d469643cbe9ee136ff80aa31b44666e10ee4abc16fbf52?s=96&d=mm&r=g","caption":"Ana Cuello Franco"},"url":"https:\/\/isimarkets.com\/es\/author\/ana-cuello-franco\/"}]}},"_links":{"self":[{"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/posts\/8298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/comments?post=8298"}],"version-history":[{"count":1,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/posts\/8298\/revisions"}],"predecessor-version":[{"id":8300,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/posts\/8298\/revisions\/8300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/media\/8297"}],"wp:attachment":[{"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/media?parent=8298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/categories?post=8298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/tags?post=8298"},{"taxonomy":"product","embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/product?post=8298"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/isimarkets.com\/es\/wp-json\/wp\/v2\/region?post=8298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}